{"id":8231,"date":"2025-04-16T11:26:42","date_gmt":"2025-04-16T09:26:42","guid":{"rendered":"https:\/\/www.kleine-wege.de\/KW\/?p=8231"},"modified":"2025-04-16T11:36:07","modified_gmt":"2025-04-16T09:36:07","slug":"kleines-kuechenexperiment-wiederverwertbar","status":"publish","type":"post","link":"https:\/\/www.kleine-wege.de\/KW\/2025\/04\/16\/kleines-kuechenexperiment-wiederverwertbar\/","title":{"rendered":"Kleines K\u00fcchenexperiment: Wiederverwertbar!"},"content":{"rendered":"<p><strong>Geschichten mit Ole:<br \/>\nFr\u00fchlingszwiebeln nachwachsen lassen<\/strong><\/p>\n<p>Lecker! Heute gibt es Pellkartoffeln mit Fr\u00fchlingsquark. Ole bereitet den Quark zu und schneidet daf\u00fcr Lauchzwiebeln in feine Ringe. Was passiert eigentlich mit dem Rest des Gem\u00fcses? Ole gibt den unteren Teil einfach in ein Wasserglas und stellt es auf die Fensterbank. Die ganze Familie staunt, wie schnell die Lauchzwiebeln nachwachsen. F\u00fcr das gemeinsame Fr\u00fchst\u00fcck am Sonntag wird das frische Gr\u00fcn auf das R\u00fchrei garniert.<\/p>\n<p>Bei der Zubereitung von Speisen mit der Zutat von Fr\u00fchlingszwiebeln bleibt oft ein Rest. <strong>Wusstest du, dass Fr\u00fchlingzwiebeln ziemlich schnell nachwachsen k\u00f6nnen?<\/strong> Eine M\u00f6glichkeit ist, das R\u00fchrei zu garnieren. <strong>Wie w\u00fcrdest du das Nachgewachsene verwenden?<\/strong><\/p>\n<p><em><strong>F\u00f6rdert:<\/strong> Eigenst\u00e4ndig sein \u2022 Handlungsplanung \u2022 soziales Miteinander: gemeinsam an einem Projekt arbeiten<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Geschichten mit Ole: Fr\u00fchlingszwiebeln nachwachsen lassen Lecker! Heute gibt es Pellkartoffeln mit Fr\u00fchlingsquark. Ole bereitet den Quark zu und schneidet daf\u00fcr Lauchzwiebeln in feine Ringe. Was passiert eigentlich mit dem Rest des Gem\u00fcses? Ole gibt den unteren Teil einfach in ein Wasserglas und stellt es auf die [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8233,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[29,38,252,253,31,255,254,135],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kleines K\u00fcchenexperiment: Wiederverwertbar! - KleineWege\u00ae<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kleine-wege.de\/KW\/2025\/04\/16\/kleines-kuechenexperiment-wiederverwertbar\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kleines K\u00fcchenexperiment: Wiederverwertbar! - KleineWege\u00ae\" \/>\n<meta property=\"og:description\" content=\"Geschichten mit Ole: Fr\u00fchlingszwiebeln nachwachsen lassen Lecker! Heute gibt es Pellkartoffeln mit Fr\u00fchlingsquark. Ole bereitet den Quark zu und schneidet daf\u00fcr Lauchzwiebeln in feine Ringe. Was passiert eigentlich mit dem Rest des Gem\u00fcses? Ole gibt den unteren Teil einfach in ein Wasserglas und stellt es auf die [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kleine-wege.de\/KW\/2025\/04\/16\/kleines-kuechenexperiment-wiederverwertbar\/\" \/>\n<meta property=\"og:site_name\" content=\"KleineWege\u00ae\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-16T09:26:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-16T09:36:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2025\/04\/KleineWege_Nachwachsen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"850\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yvette Schatz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/#website\",\"url\":\"https:\/\/www.kleine-wege.de\/KW\/\",\"name\":\"KleineWege\u00ae\",\"description\":\"F\u00f6rderung autistischer Menschen Heilp\u00e4dagogik im Konzept KleineWege\u00ae\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.kleine-wege.de\/KW\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/2025\/04\/16\/kleines-kuechenexperiment-wiederverwertbar\/#primaryimage\",\"url\":\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2025\/04\/KleineWege_Nachwachsen.jpg\",\"contentUrl\":\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2025\/04\/KleineWege_Nachwachsen.jpg\",\"width\":850,\"height\":850},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/2025\/04\/16\/kleines-kuechenexperiment-wiederverwertbar\/#webpage\",\"url\":\"https:\/\/www.kleine-wege.de\/KW\/2025\/04\/16\/kleines-kuechenexperiment-wiederverwertbar\/\",\"name\":\"Kleines K\u00fcchenexperiment: Wiederverwertbar! - KleineWege\u00ae\",\"isPartOf\":{\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/2025\/04\/16\/kleines-kuechenexperiment-wiederverwertbar\/#primaryimage\"},\"datePublished\":\"2025-04-16T09:26:42+00:00\",\"dateModified\":\"2025-04-16T09:36:07+00:00\",\"author\":{\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/#\/schema\/person\/c96664ffd154d183f315dcc75bb5b139\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/2025\/04\/16\/kleines-kuechenexperiment-wiederverwertbar\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.kleine-wege.de\/KW\/2025\/04\/16\/kleines-kuechenexperiment-wiederverwertbar\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/2025\/04\/16\/kleines-kuechenexperiment-wiederverwertbar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.kleine-wege.de\/KW\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kleines K\u00fcchenexperiment: Wiederverwertbar!\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/#\/schema\/person\/c96664ffd154d183f315dcc75bb5b139\",\"name\":\"Yvette Schatz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/81188b01651729718f1e4caa0cdc5ee1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/81188b01651729718f1e4caa0cdc5ee1?s=96&d=mm&r=g\",\"caption\":\"Yvette Schatz\"},\"sameAs\":[\"https:\/\/www.kleine-wege.de\/KW\"],\"url\":\"https:\/\/www.kleine-wege.de\/KW\/author\/yvette-schatz\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kleines K\u00fcchenexperiment: Wiederverwertbar! - KleineWege\u00ae","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kleine-wege.de\/KW\/2025\/04\/16\/kleines-kuechenexperiment-wiederverwertbar\/","og_locale":"de_DE","og_type":"article","og_title":"Kleines K\u00fcchenexperiment: Wiederverwertbar! - KleineWege\u00ae","og_description":"Geschichten mit Ole: Fr\u00fchlingszwiebeln nachwachsen lassen Lecker! Heute gibt es Pellkartoffeln mit Fr\u00fchlingsquark. Ole bereitet den Quark zu und schneidet daf\u00fcr Lauchzwiebeln in feine Ringe. Was passiert eigentlich mit dem Rest des Gem\u00fcses? Ole gibt den unteren Teil einfach in ein Wasserglas und stellt es auf die [&hellip;]","og_url":"https:\/\/www.kleine-wege.de\/KW\/2025\/04\/16\/kleines-kuechenexperiment-wiederverwertbar\/","og_site_name":"KleineWege\u00ae","article_published_time":"2025-04-16T09:26:42+00:00","article_modified_time":"2025-04-16T09:36:07+00:00","og_image":[{"width":850,"height":850,"url":"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2025\/04\/KleineWege_Nachwachsen.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Yvette Schatz","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.kleine-wege.de\/KW\/#website","url":"https:\/\/www.kleine-wege.de\/KW\/","name":"KleineWege\u00ae","description":"F\u00f6rderung autistischer Menschen Heilp\u00e4dagogik im Konzept KleineWege\u00ae","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kleine-wege.de\/KW\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kleine-wege.de\/KW\/2025\/04\/16\/kleines-kuechenexperiment-wiederverwertbar\/#primaryimage","url":"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2025\/04\/KleineWege_Nachwachsen.jpg","contentUrl":"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2025\/04\/KleineWege_Nachwachsen.jpg","width":850,"height":850},{"@type":"WebPage","@id":"https:\/\/www.kleine-wege.de\/KW\/2025\/04\/16\/kleines-kuechenexperiment-wiederverwertbar\/#webpage","url":"https:\/\/www.kleine-wege.de\/KW\/2025\/04\/16\/kleines-kuechenexperiment-wiederverwertbar\/","name":"Kleines K\u00fcchenexperiment: Wiederverwertbar! - KleineWege\u00ae","isPartOf":{"@id":"https:\/\/www.kleine-wege.de\/KW\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kleine-wege.de\/KW\/2025\/04\/16\/kleines-kuechenexperiment-wiederverwertbar\/#primaryimage"},"datePublished":"2025-04-16T09:26:42+00:00","dateModified":"2025-04-16T09:36:07+00:00","author":{"@id":"https:\/\/www.kleine-wege.de\/KW\/#\/schema\/person\/c96664ffd154d183f315dcc75bb5b139"},"breadcrumb":{"@id":"https:\/\/www.kleine-wege.de\/KW\/2025\/04\/16\/kleines-kuechenexperiment-wiederverwertbar\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kleine-wege.de\/KW\/2025\/04\/16\/kleines-kuechenexperiment-wiederverwertbar\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kleine-wege.de\/KW\/2025\/04\/16\/kleines-kuechenexperiment-wiederverwertbar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kleine-wege.de\/KW\/"},{"@type":"ListItem","position":2,"name":"Kleines K\u00fcchenexperiment: Wiederverwertbar!"}]},{"@type":"Person","@id":"https:\/\/www.kleine-wege.de\/KW\/#\/schema\/person\/c96664ffd154d183f315dcc75bb5b139","name":"Yvette Schatz","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kleine-wege.de\/KW\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/81188b01651729718f1e4caa0cdc5ee1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/81188b01651729718f1e4caa0cdc5ee1?s=96&d=mm&r=g","caption":"Yvette Schatz"},"sameAs":["https:\/\/www.kleine-wege.de\/KW"],"url":"https:\/\/www.kleine-wege.de\/KW\/author\/yvette-schatz\/"}]}},"_links":{"self":[{"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/posts\/8231"}],"collection":[{"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/comments?post=8231"}],"version-history":[{"count":3,"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/posts\/8231\/revisions"}],"predecessor-version":[{"id":8235,"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/posts\/8231\/revisions\/8235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/media\/8233"}],"wp:attachment":[{"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/media?parent=8231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/categories?post=8231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/tags?post=8231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}