{"id":3304,"date":"2021-09-18T11:49:51","date_gmt":"2021-09-18T09:49:51","guid":{"rendered":"https:\/\/www.kleine-wege.de\/KW\/?p=3304"},"modified":"2023-02-02T14:10:20","modified_gmt":"2023-02-02T13:10:20","slug":"es-ist-erntezeit-eine-aufgabenmappe-fuer-lisa","status":"publish","type":"post","link":"https:\/\/www.kleine-wege.de\/KW\/2021\/09\/18\/es-ist-erntezeit-eine-aufgabenmappe-fuer-lisa\/","title":{"rendered":"KleineWege\u00ae-Motivbogen f\u00fcr Aufgabenmappe \u201cEs ist Erntezeit!&#8220;"},"content":{"rendered":"<h6>Es ist Erntezeit! \u2013 Eine Aufgabenmappe f\u00fcr Lisa<\/h6>\n<div class=\"post_content\">\n<p>Lisa klettet die farbigen \u00c4pfel von Links nach Rechts und sortiert sie nach ihrer Farbigkeit in die K\u00f6rbe. Eine sinnvolle \u00dcbung, Zusammenh\u00e4nge zu erkennenund die Motorik zu f\u00f6rdern. Lisa \u00fcbt die bedeutsame visuelle Struktur und somit die Eins-zu-Eins-Zuordnung zu erfassen.<\/p>\n<p><strong>Hier gelangen Sie zum Download:<\/strong>\u00a0<a href=\"https:\/\/www.versandkiste-kleine-wege.de\/wp-content\/uploads\/2021\/09\/Freebie_Aufgabenmappe.pdf\"><strong>Freebie_Aufgabenmappe<\/strong><\/a><\/p>\n<p>Anleitung: Den Bogen als Schablone nutzen und die Formen auf bunten Karton \u00fcbertragen. Tipp: Alternativ k\u00f6nnen die Fl\u00e4chen mit kr\u00e4ftigen Farben ausgemalt werden. Die ausgeschnittenen Teile laminieren, nochmals ausschneiden und mit Klettpunkten versehen. Alle Objekte in die Aufgabenmappe kletten.<\/p>\n<p><a href=\"https:\/\/www.versandkiste-kleine-wege.de\/produkt\/kleine%e2%80%8awege-aufgabenmappe-einzeln\/\"><strong>Aufgabenmappen und Klettpunkte finden Sie in der KleineWege-Versandkiste.<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Es ist Erntezeit! \u2013 Eine Aufgabenmappe f\u00fcr Lisa Lisa klettet die farbigen \u00c4pfel von Links nach Rechts und sortiert sie nach ihrer Farbigkeit in die K\u00f6rbe. Eine sinnvolle \u00dcbung, Zusammenh\u00e4nge zu erkennenund die Motorik zu f\u00f6rdern. Lisa \u00fcbt die bedeutsame visuelle Struktur und somit die Eins-zu-Eins-Zuordnung zu [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3305,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[87,101,34,30,29,33,27,102,31,41,37,26,32,103],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>KleineWege\u00ae-Motivbogen f\u00fcr Aufgabenmappe \u201cEs ist Erntezeit!&quot; - KleineWege\u00ae<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kleine-wege.de\/KW\/2021\/09\/18\/es-ist-erntezeit-eine-aufgabenmappe-fuer-lisa\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KleineWege\u00ae-Motivbogen f\u00fcr Aufgabenmappe \u201cEs ist Erntezeit!&quot; - KleineWege\u00ae\" \/>\n<meta property=\"og:description\" content=\"Es ist Erntezeit! \u2013 Eine Aufgabenmappe f\u00fcr Lisa Lisa klettet die farbigen \u00c4pfel von Links nach Rechts und sortiert sie nach ihrer Farbigkeit in die K\u00f6rbe. Eine sinnvolle \u00dcbung, Zusammenh\u00e4nge zu erkennenund die Motorik zu f\u00f6rdern. Lisa \u00fcbt die bedeutsame visuelle Struktur und somit die Eins-zu-Eins-Zuordnung zu [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kleine-wege.de\/KW\/2021\/09\/18\/es-ist-erntezeit-eine-aufgabenmappe-fuer-lisa\/\" \/>\n<meta property=\"og:site_name\" content=\"KleineWege\u00ae\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-18T09:49:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-02T13:10:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Apfel_Herbst.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"850\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yvette Schatz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/#website\",\"url\":\"https:\/\/www.kleine-wege.de\/KW\/\",\"name\":\"KleineWege\u00ae\",\"description\":\"F\u00f6rderung autistischer Menschen Heilp\u00e4dagogik im Konzept KleineWege\u00ae\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.kleine-wege.de\/KW\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/2021\/09\/18\/es-ist-erntezeit-eine-aufgabenmappe-fuer-lisa\/#primaryimage\",\"url\":\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Apfel_Herbst.jpg\",\"contentUrl\":\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Apfel_Herbst.jpg\",\"width\":850,\"height\":850},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/2021\/09\/18\/es-ist-erntezeit-eine-aufgabenmappe-fuer-lisa\/#webpage\",\"url\":\"https:\/\/www.kleine-wege.de\/KW\/2021\/09\/18\/es-ist-erntezeit-eine-aufgabenmappe-fuer-lisa\/\",\"name\":\"KleineWege\u00ae-Motivbogen f\u00fcr Aufgabenmappe \u201cEs ist Erntezeit!\\\" - KleineWege\u00ae\",\"isPartOf\":{\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/2021\/09\/18\/es-ist-erntezeit-eine-aufgabenmappe-fuer-lisa\/#primaryimage\"},\"datePublished\":\"2021-09-18T09:49:51+00:00\",\"dateModified\":\"2023-02-02T13:10:20+00:00\",\"author\":{\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/#\/schema\/person\/c96664ffd154d183f315dcc75bb5b139\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/2021\/09\/18\/es-ist-erntezeit-eine-aufgabenmappe-fuer-lisa\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.kleine-wege.de\/KW\/2021\/09\/18\/es-ist-erntezeit-eine-aufgabenmappe-fuer-lisa\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/2021\/09\/18\/es-ist-erntezeit-eine-aufgabenmappe-fuer-lisa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.kleine-wege.de\/KW\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"KleineWege\u00ae-Motivbogen f\u00fcr Aufgabenmappe \u201cEs ist Erntezeit!&#8220;\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/#\/schema\/person\/c96664ffd154d183f315dcc75bb5b139\",\"name\":\"Yvette Schatz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/81188b01651729718f1e4caa0cdc5ee1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/81188b01651729718f1e4caa0cdc5ee1?s=96&d=mm&r=g\",\"caption\":\"Yvette Schatz\"},\"sameAs\":[\"https:\/\/www.kleine-wege.de\/KW\"],\"url\":\"https:\/\/www.kleine-wege.de\/KW\/author\/yvette-schatz\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KleineWege\u00ae-Motivbogen f\u00fcr Aufgabenmappe \u201cEs ist Erntezeit!\" - KleineWege\u00ae","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kleine-wege.de\/KW\/2021\/09\/18\/es-ist-erntezeit-eine-aufgabenmappe-fuer-lisa\/","og_locale":"de_DE","og_type":"article","og_title":"KleineWege\u00ae-Motivbogen f\u00fcr Aufgabenmappe \u201cEs ist Erntezeit!\" - KleineWege\u00ae","og_description":"Es ist Erntezeit! \u2013 Eine Aufgabenmappe f\u00fcr Lisa Lisa klettet die farbigen \u00c4pfel von Links nach Rechts und sortiert sie nach ihrer Farbigkeit in die K\u00f6rbe. Eine sinnvolle \u00dcbung, Zusammenh\u00e4nge zu erkennenund die Motorik zu f\u00f6rdern. Lisa \u00fcbt die bedeutsame visuelle Struktur und somit die Eins-zu-Eins-Zuordnung zu [&hellip;]","og_url":"https:\/\/www.kleine-wege.de\/KW\/2021\/09\/18\/es-ist-erntezeit-eine-aufgabenmappe-fuer-lisa\/","og_site_name":"KleineWege\u00ae","article_published_time":"2021-09-18T09:49:51+00:00","article_modified_time":"2023-02-02T13:10:20+00:00","og_image":[{"width":850,"height":850,"url":"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Apfel_Herbst.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Yvette Schatz","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.kleine-wege.de\/KW\/#website","url":"https:\/\/www.kleine-wege.de\/KW\/","name":"KleineWege\u00ae","description":"F\u00f6rderung autistischer Menschen Heilp\u00e4dagogik im Konzept KleineWege\u00ae","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kleine-wege.de\/KW\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kleine-wege.de\/KW\/2021\/09\/18\/es-ist-erntezeit-eine-aufgabenmappe-fuer-lisa\/#primaryimage","url":"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Apfel_Herbst.jpg","contentUrl":"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Apfel_Herbst.jpg","width":850,"height":850},{"@type":"WebPage","@id":"https:\/\/www.kleine-wege.de\/KW\/2021\/09\/18\/es-ist-erntezeit-eine-aufgabenmappe-fuer-lisa\/#webpage","url":"https:\/\/www.kleine-wege.de\/KW\/2021\/09\/18\/es-ist-erntezeit-eine-aufgabenmappe-fuer-lisa\/","name":"KleineWege\u00ae-Motivbogen f\u00fcr Aufgabenmappe \u201cEs ist Erntezeit!\" - KleineWege\u00ae","isPartOf":{"@id":"https:\/\/www.kleine-wege.de\/KW\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kleine-wege.de\/KW\/2021\/09\/18\/es-ist-erntezeit-eine-aufgabenmappe-fuer-lisa\/#primaryimage"},"datePublished":"2021-09-18T09:49:51+00:00","dateModified":"2023-02-02T13:10:20+00:00","author":{"@id":"https:\/\/www.kleine-wege.de\/KW\/#\/schema\/person\/c96664ffd154d183f315dcc75bb5b139"},"breadcrumb":{"@id":"https:\/\/www.kleine-wege.de\/KW\/2021\/09\/18\/es-ist-erntezeit-eine-aufgabenmappe-fuer-lisa\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kleine-wege.de\/KW\/2021\/09\/18\/es-ist-erntezeit-eine-aufgabenmappe-fuer-lisa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kleine-wege.de\/KW\/2021\/09\/18\/es-ist-erntezeit-eine-aufgabenmappe-fuer-lisa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kleine-wege.de\/KW\/"},{"@type":"ListItem","position":2,"name":"KleineWege\u00ae-Motivbogen f\u00fcr Aufgabenmappe \u201cEs ist Erntezeit!&#8220;"}]},{"@type":"Person","@id":"https:\/\/www.kleine-wege.de\/KW\/#\/schema\/person\/c96664ffd154d183f315dcc75bb5b139","name":"Yvette Schatz","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kleine-wege.de\/KW\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/81188b01651729718f1e4caa0cdc5ee1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/81188b01651729718f1e4caa0cdc5ee1?s=96&d=mm&r=g","caption":"Yvette Schatz"},"sameAs":["https:\/\/www.kleine-wege.de\/KW"],"url":"https:\/\/www.kleine-wege.de\/KW\/author\/yvette-schatz\/"}]}},"_links":{"self":[{"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/posts\/3304"}],"collection":[{"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/comments?post=3304"}],"version-history":[{"count":3,"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/posts\/3304\/revisions"}],"predecessor-version":[{"id":4876,"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/posts\/3304\/revisions\/4876"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/media\/3305"}],"wp:attachment":[{"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/media?parent=3304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/categories?post=3304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/tags?post=3304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}