{"id":3234,"date":"2018-07-05T13:05:23","date_gmt":"2018-07-05T11:05:23","guid":{"rendered":"https:\/\/www.kleine-wege.de\/KW\/?p=3234"},"modified":"2022-04-05T11:12:50","modified_gmt":"2022-04-05T09:12:50","slug":"sich-selbst-und-andere-verstehen-spiegelgeschichten-mit-hans","status":"publish","type":"post","link":"https:\/\/www.kleine-wege.de\/KW\/2018\/07\/05\/sich-selbst-und-andere-verstehen-spiegelgeschichten-mit-hans\/","title":{"rendered":"Sich selbst und andere verstehen \u2013 Spiegelgeschichten mit Hans"},"content":{"rendered":"<h1>Sich selbst und andere verstehen \u2013 Spiegelgeschichten mit Hans<\/h1>\n<div class=\"post_content\">\n<p>Hans konzentriert sich gern auf den Unterricht, denn daf\u00fcr kommt er schlie\u00dflich in die Schule. Er ist ziemlich ehrgeizig und m\u00f6chte lernen. In den Pausen erholt er sich, indem er seine Zeitschriften durchbl\u00e4ttert oder mit anderen \u00fcber sein Lieblingsthema \u201eAlte H\u00e4user\u201c plaudern m\u00f6chte.<\/p>\n<p>Manchmal bemerkt er, dass die anderen lachen. Lachen sie \u00fcber ihn? Warum?<br \/>\nDann kann er richtig \u00e4rgerlich werden, obwohl die anderen sagen, es ginge doch gar nicht um ihn.<\/p>\n<p>Hans f\u00e4llt es schwer, zu verstehen, was seine Mitsch\u00fclerinnen und Mitsch\u00fcler w\u00e4hrend des Unterrichts oder in den Pausen bereden. Er m\u00f6chte herausfinden, wie die anderen Menschen funktionieren, was sie denken und f\u00fchlen, warum sie lachen und in Gruppen zusammenstehen und reden.<\/p>\n<p>In unserer \u00dcbung aus unserem KleineWege\u00ae-Sommerprojekt \u201eDer Spiegel\u201c setzten wir zwei Figuren vor einen Spiegel und \u00fcberlegten gemeinsam:<br \/>\nWas k\u00f6nnten die beiden da erz\u00e4hlen? Warum verstecken sie sich? Ist es ein Streitgespr\u00e4ch oder lachen sie \u00fcber etwas?<\/p>\n<p>Stell Dir vor, im Spiegel k\u00f6nntest Du die Gesichter sehen. Was w\u00fcrde sich \u00e4ndern? Welche Informationen aus der Umwelt ben\u00f6tigst Du, um das Gespr\u00e4ch richtig einordnen zu k\u00f6nnen? Sind die beiden im Klassenraum oder zu Hause? \u2026<\/p>\n<p>F\u00fcr unseren Hans war es spannend zu beobachten, dass sich ein Dialog abh\u00e4ngig von den jeweiligen Gesichtsausdr\u00fccken ver\u00e4ndern kann.<\/p>\n<p><strong>Seine wichtigste Erkenntnis unserer \u00dcbung:<\/strong> Jeder Mensch, ob mit oder ohne Autismus, kann Gef\u00fchle und Gedanken des anderen nur erraten. Oft fordert es echte Detektivarbeit, die anderen zu entschl\u00fcsseln und die Situation einsch\u00e4tzen zu k\u00f6nnen.<\/p>\n<\/div>\n<div class=\"post_content\">\n<p>&nbsp;<\/p>\n<style type=\"text\/css\">.fusion-gallery-1 .fusion-gallery-image {border:0px solid #e2e2e2;}<\/style><div class=\"fusion-gallery fusion-gallery-container fusion-grid-3 fusion-columns-total-6 fusion-gallery-layout-grid fusion-gallery-1\" style=\"margin:-11px;\"><div style=\"padding:11.5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-zoomin\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_1.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_1.jpg\" width=\"1200\" height=\"750\" alt=\"\" title=\"KleineWege_SozialeKompetenzen_1\" aria-label=\"KleineWege_SozialeKompetenzen_1\" class=\"img-responsive wp-image-3235\" srcset=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_1-200x125.jpg 200w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_1-400x250.jpg 400w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_1-600x375.jpg 600w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_1-800x500.jpg 800w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_1.jpg 1200w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 426px, (min-width: 712px) 639px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div style=\"padding:11.5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-zoomin\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_2.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_2.jpg\" width=\"1200\" height=\"750\" alt=\"\" title=\"KleineWege_SozialeKompetenzen_2\" aria-label=\"KleineWege_SozialeKompetenzen_2\" class=\"img-responsive wp-image-3236\" srcset=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_2-200x125.jpg 200w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_2-400x250.jpg 400w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_2-600x375.jpg 600w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_2-800x500.jpg 800w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_2.jpg 1200w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 426px, (min-width: 712px) 639px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div style=\"padding:11.5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-zoomin\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_3.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_3.jpg\" width=\"1200\" height=\"750\" alt=\"\" title=\"KleineWege_SozialeKompetenzen_3\" aria-label=\"KleineWege_SozialeKompetenzen_3\" class=\"img-responsive wp-image-3237\" srcset=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_3-200x125.jpg 200w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_3-400x250.jpg 400w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_3-600x375.jpg 600w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_3-800x500.jpg 800w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_3.jpg 1200w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 426px, (min-width: 712px) 639px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div class=\"clearfix\"><\/div><div style=\"padding:11.5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-zoomin\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_4.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_4.jpg\" width=\"1200\" height=\"750\" alt=\"\" title=\"KleineWege_SozialeKompetenzen_4\" aria-label=\"KleineWege_SozialeKompetenzen_4\" class=\"img-responsive wp-image-3238\" srcset=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_4-200x125.jpg 200w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_4-400x250.jpg 400w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_4-600x375.jpg 600w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_4-800x500.jpg 800w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_4.jpg 1200w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 426px, (min-width: 712px) 639px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div style=\"padding:11.5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-zoomin\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_5.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_5.jpg\" width=\"1200\" height=\"750\" alt=\"\" title=\"KleineWege_SozialeKompetenzen_5\" aria-label=\"KleineWege_SozialeKompetenzen_5\" class=\"img-responsive wp-image-3239\" srcset=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_5-200x125.jpg 200w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_5-400x250.jpg 400w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_5-600x375.jpg 600w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_5-800x500.jpg 800w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_5.jpg 1200w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 426px, (min-width: 712px) 639px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div style=\"padding:11.5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-zoomin\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_6.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_6.jpg\" width=\"1200\" height=\"750\" alt=\"\" title=\"KleineWege_SozialeKompetenzen_6\" aria-label=\"KleineWege_SozialeKompetenzen_6\" class=\"img-responsive wp-image-3240\" srcset=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_6-200x125.jpg 200w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_6-400x250.jpg 400w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_6-600x375.jpg 600w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_6-800x500.jpg 800w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_6.jpg 1200w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 426px, (min-width: 712px) 639px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div class=\"clearfix\"><\/div><\/div>\n<p>&nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sich selbst und andere verstehen \u2013 Spiegelgeschichten mit Hans Hans konzentriert sich gern auf den Unterricht, denn daf\u00fcr kommt er schlie\u00dflich in die Schule. Er ist ziemlich ehrgeizig und m\u00f6chte lernen. In den Pausen erholt er sich, indem er seine Zeitschriften durchbl\u00e4ttert oder mit anderen \u00fcber sein [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3241,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[30,29,33,27,25,31,28,26,20,22,24,21,23,18,32,19],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sich selbst und andere verstehen \u2013 Spiegelgeschichten mit Hans - KleineWege\u00ae<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kleine-wege.de\/KW\/2018\/07\/05\/sich-selbst-und-andere-verstehen-spiegelgeschichten-mit-hans\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sich selbst und andere verstehen \u2013 Spiegelgeschichten mit Hans - KleineWege\u00ae\" \/>\n<meta property=\"og:description\" content=\"Sich selbst und andere verstehen \u2013 Spiegelgeschichten mit Hans Hans konzentriert sich gern auf den Unterricht, denn daf\u00fcr kommt er schlie\u00dflich in die Schule. Er ist ziemlich ehrgeizig und m\u00f6chte lernen. In den Pausen erholt er sich, indem er seine Zeitschriften durchbl\u00e4ttert oder mit anderen \u00fcber sein [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kleine-wege.de\/KW\/2018\/07\/05\/sich-selbst-und-andere-verstehen-spiegelgeschichten-mit-hans\/\" \/>\n<meta property=\"og:site_name\" content=\"KleineWege\u00ae\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-05T11:05:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-05T09:12:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_B.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"850\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yvette Schatz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/#website\",\"url\":\"https:\/\/www.kleine-wege.de\/KW\/\",\"name\":\"KleineWege\u00ae\",\"description\":\"F\u00f6rderung autistischer Menschen Heilp\u00e4dagogik im Konzept KleineWege\u00ae\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.kleine-wege.de\/KW\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/2018\/07\/05\/sich-selbst-und-andere-verstehen-spiegelgeschichten-mit-hans\/#primaryimage\",\"url\":\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_B.jpg\",\"contentUrl\":\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_B.jpg\",\"width\":850,\"height\":850},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/2018\/07\/05\/sich-selbst-und-andere-verstehen-spiegelgeschichten-mit-hans\/#webpage\",\"url\":\"https:\/\/www.kleine-wege.de\/KW\/2018\/07\/05\/sich-selbst-und-andere-verstehen-spiegelgeschichten-mit-hans\/\",\"name\":\"Sich selbst und andere verstehen \u2013 Spiegelgeschichten mit Hans - KleineWege\u00ae\",\"isPartOf\":{\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/2018\/07\/05\/sich-selbst-und-andere-verstehen-spiegelgeschichten-mit-hans\/#primaryimage\"},\"datePublished\":\"2018-07-05T11:05:23+00:00\",\"dateModified\":\"2022-04-05T09:12:50+00:00\",\"author\":{\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/#\/schema\/person\/c96664ffd154d183f315dcc75bb5b139\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/2018\/07\/05\/sich-selbst-und-andere-verstehen-spiegelgeschichten-mit-hans\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.kleine-wege.de\/KW\/2018\/07\/05\/sich-selbst-und-andere-verstehen-spiegelgeschichten-mit-hans\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/2018\/07\/05\/sich-selbst-und-andere-verstehen-spiegelgeschichten-mit-hans\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.kleine-wege.de\/KW\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sich selbst und andere verstehen \u2013 Spiegelgeschichten mit Hans\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/#\/schema\/person\/c96664ffd154d183f315dcc75bb5b139\",\"name\":\"Yvette Schatz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/81188b01651729718f1e4caa0cdc5ee1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/81188b01651729718f1e4caa0cdc5ee1?s=96&d=mm&r=g\",\"caption\":\"Yvette Schatz\"},\"sameAs\":[\"https:\/\/www.kleine-wege.de\/KW\"],\"url\":\"https:\/\/www.kleine-wege.de\/KW\/author\/yvette-schatz\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sich selbst und andere verstehen \u2013 Spiegelgeschichten mit Hans - KleineWege\u00ae","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kleine-wege.de\/KW\/2018\/07\/05\/sich-selbst-und-andere-verstehen-spiegelgeschichten-mit-hans\/","og_locale":"de_DE","og_type":"article","og_title":"Sich selbst und andere verstehen \u2013 Spiegelgeschichten mit Hans - KleineWege\u00ae","og_description":"Sich selbst und andere verstehen \u2013 Spiegelgeschichten mit Hans Hans konzentriert sich gern auf den Unterricht, denn daf\u00fcr kommt er schlie\u00dflich in die Schule. Er ist ziemlich ehrgeizig und m\u00f6chte lernen. In den Pausen erholt er sich, indem er seine Zeitschriften durchbl\u00e4ttert oder mit anderen \u00fcber sein [&hellip;]","og_url":"https:\/\/www.kleine-wege.de\/KW\/2018\/07\/05\/sich-selbst-und-andere-verstehen-spiegelgeschichten-mit-hans\/","og_site_name":"KleineWege\u00ae","article_published_time":"2018-07-05T11:05:23+00:00","article_modified_time":"2022-04-05T09:12:50+00:00","og_image":[{"width":850,"height":850,"url":"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_B.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Yvette Schatz","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.kleine-wege.de\/KW\/#website","url":"https:\/\/www.kleine-wege.de\/KW\/","name":"KleineWege\u00ae","description":"F\u00f6rderung autistischer Menschen Heilp\u00e4dagogik im Konzept KleineWege\u00ae","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kleine-wege.de\/KW\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kleine-wege.de\/KW\/2018\/07\/05\/sich-selbst-und-andere-verstehen-spiegelgeschichten-mit-hans\/#primaryimage","url":"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_B.jpg","contentUrl":"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_SozialeKompetenzen_B.jpg","width":850,"height":850},{"@type":"WebPage","@id":"https:\/\/www.kleine-wege.de\/KW\/2018\/07\/05\/sich-selbst-und-andere-verstehen-spiegelgeschichten-mit-hans\/#webpage","url":"https:\/\/www.kleine-wege.de\/KW\/2018\/07\/05\/sich-selbst-und-andere-verstehen-spiegelgeschichten-mit-hans\/","name":"Sich selbst und andere verstehen \u2013 Spiegelgeschichten mit Hans - KleineWege\u00ae","isPartOf":{"@id":"https:\/\/www.kleine-wege.de\/KW\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kleine-wege.de\/KW\/2018\/07\/05\/sich-selbst-und-andere-verstehen-spiegelgeschichten-mit-hans\/#primaryimage"},"datePublished":"2018-07-05T11:05:23+00:00","dateModified":"2022-04-05T09:12:50+00:00","author":{"@id":"https:\/\/www.kleine-wege.de\/KW\/#\/schema\/person\/c96664ffd154d183f315dcc75bb5b139"},"breadcrumb":{"@id":"https:\/\/www.kleine-wege.de\/KW\/2018\/07\/05\/sich-selbst-und-andere-verstehen-spiegelgeschichten-mit-hans\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kleine-wege.de\/KW\/2018\/07\/05\/sich-selbst-und-andere-verstehen-spiegelgeschichten-mit-hans\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kleine-wege.de\/KW\/2018\/07\/05\/sich-selbst-und-andere-verstehen-spiegelgeschichten-mit-hans\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kleine-wege.de\/KW\/"},{"@type":"ListItem","position":2,"name":"Sich selbst und andere verstehen \u2013 Spiegelgeschichten mit Hans"}]},{"@type":"Person","@id":"https:\/\/www.kleine-wege.de\/KW\/#\/schema\/person\/c96664ffd154d183f315dcc75bb5b139","name":"Yvette Schatz","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kleine-wege.de\/KW\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/81188b01651729718f1e4caa0cdc5ee1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/81188b01651729718f1e4caa0cdc5ee1?s=96&d=mm&r=g","caption":"Yvette Schatz"},"sameAs":["https:\/\/www.kleine-wege.de\/KW"],"url":"https:\/\/www.kleine-wege.de\/KW\/author\/yvette-schatz\/"}]}},"_links":{"self":[{"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/posts\/3234"}],"collection":[{"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/comments?post=3234"}],"version-history":[{"count":3,"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/posts\/3234\/revisions"}],"predecessor-version":[{"id":4039,"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/posts\/3234\/revisions\/4039"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/media\/3241"}],"wp:attachment":[{"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/media?parent=3234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/categories?post=3234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/tags?post=3234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}