{"id":3097,"date":"2021-12-10T11:56:07","date_gmt":"2021-12-10T10:56:07","guid":{"rendered":"https:\/\/www.kleine-wege.de\/KW\/?p=3097"},"modified":"2023-02-02T14:09:16","modified_gmt":"2023-02-02T13:09:16","slug":"kostuemideen-fuer-das-faschingsfest-im-kindergarten-wenig-aufwand-grosse-wirkung-2","status":"publish","type":"post","link":"https:\/\/www.kleine-wege.de\/KW\/2021\/12\/10\/kostuemideen-fuer-das-faschingsfest-im-kindergarten-wenig-aufwand-grosse-wirkung-2\/","title":{"rendered":"KleineWege\u00ae-Motivbogen f\u00fcr Aufgabenmappe \u201cLichter an\u201d"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#e2e2e2;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:calc( 1300px + 0px );margin-left: calc(-0px \/ 2 );margin-right: calc(-0px \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-1\" style=\"transform:translate3d(0,0,0);\"><h6 style=\"font-size: 36px; font-family: Roboto; font-weight: bold; color: #686868;\" data-fusion-font=\"true\" data-fusion-google-font=\"Roboto\" data-fusion-google-variant=\"700\">KleineWege\u00ae-Motivbogen f\u00fcr Aufgabenmappe \u201cLichter an\u201d<\/h6>\n<div class=\"post_content\">\n<p><strong>Inspiration aus der Ideenkiste \u2013 Eine Aufgabenmappe f\u00fcr Lisa<\/strong><\/p>\n<p>Es ist Weihnachtszeit. Der Tannenbaum auf dem Markt in der Stadt leuchtet. Heute macht Lisa das Licht an, indem sie in der Aufgabenmappe die hellen Punkte auf den Weihnachtsbaum anbringt. Dabei achtet Lisa genau auf die Zuordnungspunkte.<\/p>\n<p><strong>Downloaden Sie unseren Schablonen-Bogen zum Nachbauen dieser Aufgabe hier:<\/strong> <a href=\"https:\/\/www.versandkiste-kleine-wege.de\/wp-content\/uploads\/2021\/12\/KW_Freebie.pdf\"><strong>Freebie_Aufgabenmappe<\/strong><\/a><strong><br \/>\n<\/strong><\/p>\n<p><strong>Anleitung:<\/strong><\/p>\n<p>Den Bogen als Schablone nutzen und die Formen auf entsprechend farbigen Karton \u00fcbertragen und ausschneiden. 12 gelbe Punkte laminieren, nochmals ausschneiden und mit Hakenpunkten versehen. So sind die Punkte stabil. Den Tannenbaum, Stamm und Waldboden direkt vollfl\u00e4chig auf die Mappe kleben. Nach dem Trocknen die Objekte mit Flausch- bzw. Hakenpunkten versehen.<\/p>\n<p><strong>TIPP:<\/strong> Diese Aufgabe ist ver\u00e4nderbar. Nutzen Sie das KleineWege-Aufgabenmappen-Set <strong>\u2013 <\/strong>Konfetti , um den Tannenbaum mit bunten Kugeln zu schm\u00fccken! Das Set enth\u00e4lt einige der Materialien f\u00fcr diese Aufgabenmappe.<\/p>\n<p><a href=\"https:\/\/www.versandkiste-kleine-wege.de\/produkt\/kleine%e2%80%8awege-aufgabenmappe-einzeln\/\"><strong>Aufgabenmappen und Klettpunkte finden Sie in der KleineWege-Versandkiste.<\/strong><\/a><\/p>\n<\/div>\n<\/div><style type=\"text\/css\">.fusion-gallery-1 .fusion-gallery-image {border:0px solid #e2e2e2;}<\/style><div class=\"fusion-gallery fusion-gallery-container fusion-grid-3 fusion-columns-total-5 fusion-gallery-layout-grid fusion-gallery-1\" style=\"margin:-17px;\"><div style=\"padding:17.5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-zoomin\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe1.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe1.jpg\" width=\"945\" height=\"590\" alt=\"\" title=\"KleineWege_Aufgabenmappe1\" aria-label=\"KleineWege_Aufgabenmappe1\" class=\"img-responsive wp-image-3136\" srcset=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe1-200x125.jpg 200w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe1-400x250.jpg 400w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe1-600x375.jpg 600w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe1-800x499.jpg 800w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe1.jpg 945w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 422px, (min-width: 712px) 633px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div style=\"padding:17.5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-zoomin\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KeineWege_Aufgabenmappe5.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KeineWege_Aufgabenmappe5.jpg\" width=\"945\" height=\"590\" alt=\"KeineWege Aufgabenmappe\" title=\"KeineWege_Aufgabenmappe5\" aria-label=\"KeineWege_Aufgabenmappe5\" class=\"img-responsive wp-image-3135\" srcset=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KeineWege_Aufgabenmappe5-200x125.jpg 200w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KeineWege_Aufgabenmappe5-400x250.jpg 400w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KeineWege_Aufgabenmappe5-600x375.jpg 600w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KeineWege_Aufgabenmappe5-800x499.jpg 800w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KeineWege_Aufgabenmappe5.jpg 945w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 422px, (min-width: 712px) 633px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div style=\"padding:17.5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-zoomin\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe4.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe4.jpg\" width=\"945\" height=\"590\" alt=\"\" title=\"KleineWege_Aufgabenmappe4\" aria-label=\"KleineWege_Aufgabenmappe4\" class=\"img-responsive wp-image-3134\" srcset=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe4-200x125.jpg 200w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe4-400x250.jpg 400w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe4-600x375.jpg 600w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe4-800x499.jpg 800w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe4.jpg 945w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 422px, (min-width: 712px) 633px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div class=\"clearfix\"><\/div><div style=\"padding:17.5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-zoomin\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe3.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe3.jpg\" width=\"945\" height=\"590\" alt=\"\" title=\"KleineWege_Aufgabenmappe3\" aria-label=\"KleineWege_Aufgabenmappe3\" class=\"img-responsive wp-image-3133\" srcset=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe3-200x125.jpg 200w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe3-400x250.jpg 400w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe3-600x375.jpg 600w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe3-800x499.jpg 800w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe3.jpg 945w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 422px, (min-width: 712px) 633px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div style=\"padding:17.5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-zoomin\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe2.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe2.jpg\" width=\"945\" height=\"590\" alt=\"\" title=\"KleineWege_Aufgabenmappe2\" aria-label=\"KleineWege_Aufgabenmappe2\" class=\"img-responsive wp-image-3132\" srcset=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe2-200x125.jpg 200w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe2-400x250.jpg 400w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe2-600x375.jpg 600w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe2-800x499.jpg 800w, https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe2.jpg 945w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 422px, (min-width: 712px) 633px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-0{width:100% !important;margin-top : 0px;margin-bottom : 0px;}.fusion-builder-column-0 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 0px;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 0px;}@media only screen and (max-width:1177px) {.fusion-body .fusion-builder-column-0{width:100% !important;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 0px;margin-left : 0px;}}@media only screen and (max-width:700px) {.fusion-body .fusion-builder-column-0{width:100% !important;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 0px;margin-left : 0px;}}<\/style><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-1{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":3230,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[34,30,29,33,36,39,25,31,41,37,35,32,40],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>KleineWege\u00ae-Motivbogen f\u00fcr Aufgabenmappe \u201cLichter an\u201d - KleineWege\u00ae<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kleine-wege.de\/KW\/2021\/12\/10\/kostuemideen-fuer-das-faschingsfest-im-kindergarten-wenig-aufwand-grosse-wirkung-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KleineWege\u00ae-Motivbogen f\u00fcr Aufgabenmappe \u201cLichter an\u201d - KleineWege\u00ae\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kleine-wege.de\/KW\/2021\/12\/10\/kostuemideen-fuer-das-faschingsfest-im-kindergarten-wenig-aufwand-grosse-wirkung-2\/\" \/>\n<meta property=\"og:site_name\" content=\"KleineWege\u00ae\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-10T10:56:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-02T13:09:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe_B.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"850\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yvette Schatz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/#website\",\"url\":\"https:\/\/www.kleine-wege.de\/KW\/\",\"name\":\"KleineWege\u00ae\",\"description\":\"F\u00f6rderung autistischer Menschen Heilp\u00e4dagogik im Konzept KleineWege\u00ae\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.kleine-wege.de\/KW\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/2021\/12\/10\/kostuemideen-fuer-das-faschingsfest-im-kindergarten-wenig-aufwand-grosse-wirkung-2\/#primaryimage\",\"url\":\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe_B.jpg\",\"contentUrl\":\"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe_B.jpg\",\"width\":850,\"height\":850,\"caption\":\"KleineWege_Aufgabenmappe\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/2021\/12\/10\/kostuemideen-fuer-das-faschingsfest-im-kindergarten-wenig-aufwand-grosse-wirkung-2\/#webpage\",\"url\":\"https:\/\/www.kleine-wege.de\/KW\/2021\/12\/10\/kostuemideen-fuer-das-faschingsfest-im-kindergarten-wenig-aufwand-grosse-wirkung-2\/\",\"name\":\"KleineWege\u00ae-Motivbogen f\u00fcr Aufgabenmappe \u201cLichter an\u201d - KleineWege\u00ae\",\"isPartOf\":{\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/2021\/12\/10\/kostuemideen-fuer-das-faschingsfest-im-kindergarten-wenig-aufwand-grosse-wirkung-2\/#primaryimage\"},\"datePublished\":\"2021-12-10T10:56:07+00:00\",\"dateModified\":\"2023-02-02T13:09:16+00:00\",\"author\":{\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/#\/schema\/person\/c96664ffd154d183f315dcc75bb5b139\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/2021\/12\/10\/kostuemideen-fuer-das-faschingsfest-im-kindergarten-wenig-aufwand-grosse-wirkung-2\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.kleine-wege.de\/KW\/2021\/12\/10\/kostuemideen-fuer-das-faschingsfest-im-kindergarten-wenig-aufwand-grosse-wirkung-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/2021\/12\/10\/kostuemideen-fuer-das-faschingsfest-im-kindergarten-wenig-aufwand-grosse-wirkung-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.kleine-wege.de\/KW\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"KleineWege\u00ae-Motivbogen f\u00fcr Aufgabenmappe \u201cLichter an\u201d\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/#\/schema\/person\/c96664ffd154d183f315dcc75bb5b139\",\"name\":\"Yvette Schatz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.kleine-wege.de\/KW\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/81188b01651729718f1e4caa0cdc5ee1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/81188b01651729718f1e4caa0cdc5ee1?s=96&d=mm&r=g\",\"caption\":\"Yvette Schatz\"},\"sameAs\":[\"https:\/\/www.kleine-wege.de\/KW\"],\"url\":\"https:\/\/www.kleine-wege.de\/KW\/author\/yvette-schatz\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KleineWege\u00ae-Motivbogen f\u00fcr Aufgabenmappe \u201cLichter an\u201d - KleineWege\u00ae","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kleine-wege.de\/KW\/2021\/12\/10\/kostuemideen-fuer-das-faschingsfest-im-kindergarten-wenig-aufwand-grosse-wirkung-2\/","og_locale":"de_DE","og_type":"article","og_title":"KleineWege\u00ae-Motivbogen f\u00fcr Aufgabenmappe \u201cLichter an\u201d - KleineWege\u00ae","og_url":"https:\/\/www.kleine-wege.de\/KW\/2021\/12\/10\/kostuemideen-fuer-das-faschingsfest-im-kindergarten-wenig-aufwand-grosse-wirkung-2\/","og_site_name":"KleineWege\u00ae","article_published_time":"2021-12-10T10:56:07+00:00","article_modified_time":"2023-02-02T13:09:16+00:00","og_image":[{"width":850,"height":850,"url":"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe_B.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Yvette Schatz","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.kleine-wege.de\/KW\/#website","url":"https:\/\/www.kleine-wege.de\/KW\/","name":"KleineWege\u00ae","description":"F\u00f6rderung autistischer Menschen Heilp\u00e4dagogik im Konzept KleineWege\u00ae","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kleine-wege.de\/KW\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kleine-wege.de\/KW\/2021\/12\/10\/kostuemideen-fuer-das-faschingsfest-im-kindergarten-wenig-aufwand-grosse-wirkung-2\/#primaryimage","url":"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe_B.jpg","contentUrl":"https:\/\/www.kleine-wege.de\/KW\/wp-content\/uploads\/2022\/01\/KleineWege_Aufgabenmappe_B.jpg","width":850,"height":850,"caption":"KleineWege_Aufgabenmappe"},{"@type":"WebPage","@id":"https:\/\/www.kleine-wege.de\/KW\/2021\/12\/10\/kostuemideen-fuer-das-faschingsfest-im-kindergarten-wenig-aufwand-grosse-wirkung-2\/#webpage","url":"https:\/\/www.kleine-wege.de\/KW\/2021\/12\/10\/kostuemideen-fuer-das-faschingsfest-im-kindergarten-wenig-aufwand-grosse-wirkung-2\/","name":"KleineWege\u00ae-Motivbogen f\u00fcr Aufgabenmappe \u201cLichter an\u201d - KleineWege\u00ae","isPartOf":{"@id":"https:\/\/www.kleine-wege.de\/KW\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kleine-wege.de\/KW\/2021\/12\/10\/kostuemideen-fuer-das-faschingsfest-im-kindergarten-wenig-aufwand-grosse-wirkung-2\/#primaryimage"},"datePublished":"2021-12-10T10:56:07+00:00","dateModified":"2023-02-02T13:09:16+00:00","author":{"@id":"https:\/\/www.kleine-wege.de\/KW\/#\/schema\/person\/c96664ffd154d183f315dcc75bb5b139"},"breadcrumb":{"@id":"https:\/\/www.kleine-wege.de\/KW\/2021\/12\/10\/kostuemideen-fuer-das-faschingsfest-im-kindergarten-wenig-aufwand-grosse-wirkung-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kleine-wege.de\/KW\/2021\/12\/10\/kostuemideen-fuer-das-faschingsfest-im-kindergarten-wenig-aufwand-grosse-wirkung-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kleine-wege.de\/KW\/2021\/12\/10\/kostuemideen-fuer-das-faschingsfest-im-kindergarten-wenig-aufwand-grosse-wirkung-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kleine-wege.de\/KW\/"},{"@type":"ListItem","position":2,"name":"KleineWege\u00ae-Motivbogen f\u00fcr Aufgabenmappe \u201cLichter an\u201d"}]},{"@type":"Person","@id":"https:\/\/www.kleine-wege.de\/KW\/#\/schema\/person\/c96664ffd154d183f315dcc75bb5b139","name":"Yvette Schatz","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kleine-wege.de\/KW\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/81188b01651729718f1e4caa0cdc5ee1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/81188b01651729718f1e4caa0cdc5ee1?s=96&d=mm&r=g","caption":"Yvette Schatz"},"sameAs":["https:\/\/www.kleine-wege.de\/KW"],"url":"https:\/\/www.kleine-wege.de\/KW\/author\/yvette-schatz\/"}]}},"_links":{"self":[{"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/posts\/3097"}],"collection":[{"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/comments?post=3097"}],"version-history":[{"count":10,"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/posts\/3097\/revisions"}],"predecessor-version":[{"id":4875,"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/posts\/3097\/revisions\/4875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/media\/3230"}],"wp:attachment":[{"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/media?parent=3097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/categories?post=3097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kleine-wege.de\/KW\/wp-json\/wp\/v2\/tags?post=3097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}